{"id":8352,"date":"2024-01-29T15:50:02","date_gmt":"2024-01-29T14:50:02","guid":{"rendered":"https:\/\/europauto2.com\/?post_type=product&#038;p=8352"},"modified":"2025-01-16T17:49:02","modified_gmt":"2025-01-16T16:49:02","slug":"porsche-911-911-991-carrera-s-2012-2019","status":"publish","type":"product","link":"https:\/\/europauto2.com\/fr\/loja\/porsche-911-911-991-carrera-s-2012-2019\/","title":{"rendered":"PORSCHE 911-991 \/ CARRERA S 2012-2019"},"content":{"rendered":"<p>Tapis de moquette r\u00e9alis\u00e9s sur mesure pour la marque et le mod\u00e8le choisis. Enti\u00e8rement personnalisables en fonction des pr\u00e9f\u00e9rences de chaque client.<\/p>","protected":false},"excerpt":{"rendered":"<p>Tapis de moquette r\u00e9alis\u00e9s sur mesure pour la marque et le mod\u00e8le choisis. Enti\u00e8rement personnalisables en fonction des pr\u00e9f\u00e9rences de chaque client.<\/p>","protected":false},"featured_media":17070,"comment_status":"open","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_cat":[162,883,194],"product_tag":[],"class_list":{"0":"post-8352","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tapetes-alcatifa","7":"product_cat-883","8":"product_cat-porsche","9":"product_shipping_class-conjunto-de-tapetes","11":"first","12":"instock","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PORSCHE 911 911-991 \/ CARRERA S 2012-2019 - Europauto 2<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europauto2.com\/fr\/loja\/porsche-911-911-991-carrera-s-2012-2019\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PORSCHE 911 911-991 \/ CARRERA S 2012-2019 - Europauto 2\" \/>\n<meta property=\"og:description\" content=\"Tapetes em alcatifa feitos por medida para a marca e modelo selecionados. Totalmente personaliz\u00e1veis de acordo com as prefer\u00eancias de cada cliente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europauto2.com\/fr\/loja\/porsche-911-911-991-carrera-s-2012-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Europauto 2\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-16T16:49:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europauto2.com\/wp-content\/uploads\/2024\/01\/PORSCHE-911-911-991-_-CARRERA-S-2012-2019-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1182\" \/>\n\t<meta property=\"og:image:height\" content=\"1182\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/europauto2.com\\\/loja\\\/porsche-911-911-991-carrera-s-2012-2019\\\/\",\"url\":\"https:\\\/\\\/europauto2.com\\\/loja\\\/porsche-911-911-991-carrera-s-2012-2019\\\/\",\"name\":\"PORSCHE 911 911-991 \\\/ CARRERA S 2012-2019 - Europauto 2\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/europauto2.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/europauto2.com\\\/loja\\\/porsche-911-911-991-carrera-s-2012-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/europauto2.com\\\/loja\\\/porsche-911-911-991-carrera-s-2012-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/europauto2.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/PORSCHE-911-911-991-_-CARRERA-S-2012-2019-1.png\",\"datePublished\":\"2024-01-29T14:50:02+00:00\",\"dateModified\":\"2025-01-16T16:49:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/europauto2.com\\\/loja\\\/porsche-911-911-991-carrera-s-2012-2019\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/europauto2.com\\\/loja\\\/porsche-911-911-991-carrera-s-2012-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/europauto2.com\\\/loja\\\/porsche-911-911-991-carrera-s-2012-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/europauto2.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/PORSCHE-911-911-991-_-CARRERA-S-2012-2019-1.png\",\"contentUrl\":\"https:\\\/\\\/europauto2.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/PORSCHE-911-911-991-_-CARRERA-S-2012-2019-1.png\",\"width\":1182,\"height\":1182},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/europauto2.com\\\/loja\\\/porsche-911-911-991-carrera-s-2012-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/europauto2.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/europauto2.com\\\/pt\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PORSCHE 911 911-991 \\\/ CARRERA S 2012-2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/europauto2.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/europauto2.com\\\/pt\\\/\",\"name\":\"Europauto 2\",\"description\":\"by IALP Communication\",\"publisher\":{\"@id\":\"https:\\\/\\\/europauto2.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/europauto2.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/europauto2.com\\\/pt\\\/#organization\",\"name\":\"Europauto 2\",\"url\":\"https:\\\/\\\/europauto2.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/europauto2.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/europauto2.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IALP-LOGO.webp\",\"contentUrl\":\"https:\\\/\\\/europauto2.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IALP-LOGO.webp\",\"width\":591,\"height\":591,\"caption\":\"Europauto 2\"},\"image\":{\"@id\":\"https:\\\/\\\/europauto2.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PORSCHE 911 911-991 \/ CARRERA S 2012-2019 - Europauto 2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europauto2.com\/fr\/loja\/porsche-911-911-991-carrera-s-2012-2019\/","og_locale":"fr_FR","og_type":"article","og_title":"PORSCHE 911 911-991 \/ CARRERA S 2012-2019 - Europauto 2","og_description":"Tapetes em alcatifa feitos por medida para a marca e modelo selecionados. Totalmente personaliz\u00e1veis de acordo com as prefer\u00eancias de cada cliente.","og_url":"https:\/\/europauto2.com\/fr\/loja\/porsche-911-911-991-carrera-s-2012-2019\/","og_site_name":"Europauto 2","article_modified_time":"2025-01-16T16:49:02+00:00","og_image":[{"width":1182,"height":1182,"url":"https:\/\/europauto2.com\/wp-content\/uploads\/2024\/01\/PORSCHE-911-911-991-_-CARRERA-S-2012-2019-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/europauto2.com\/loja\/porsche-911-911-991-carrera-s-2012-2019\/","url":"https:\/\/europauto2.com\/loja\/porsche-911-911-991-carrera-s-2012-2019\/","name":"PORSCHE 911 911-991 \/ CARRERA S 2012-2019 - Europauto 2","isPartOf":{"@id":"https:\/\/europauto2.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europauto2.com\/loja\/porsche-911-911-991-carrera-s-2012-2019\/#primaryimage"},"image":{"@id":"https:\/\/europauto2.com\/loja\/porsche-911-911-991-carrera-s-2012-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/europauto2.com\/wp-content\/uploads\/2024\/01\/PORSCHE-911-911-991-_-CARRERA-S-2012-2019-1.png","datePublished":"2024-01-29T14:50:02+00:00","dateModified":"2025-01-16T16:49:02+00:00","breadcrumb":{"@id":"https:\/\/europauto2.com\/loja\/porsche-911-911-991-carrera-s-2012-2019\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europauto2.com\/loja\/porsche-911-911-991-carrera-s-2012-2019\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/europauto2.com\/loja\/porsche-911-911-991-carrera-s-2012-2019\/#primaryimage","url":"https:\/\/europauto2.com\/wp-content\/uploads\/2024\/01\/PORSCHE-911-911-991-_-CARRERA-S-2012-2019-1.png","contentUrl":"https:\/\/europauto2.com\/wp-content\/uploads\/2024\/01\/PORSCHE-911-911-991-_-CARRERA-S-2012-2019-1.png","width":1182,"height":1182},{"@type":"BreadcrumbList","@id":"https:\/\/europauto2.com\/loja\/porsche-911-911-991-carrera-s-2012-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/europauto2.com\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/europauto2.com\/pt\/loja\/"},{"@type":"ListItem","position":3,"name":"PORSCHE 911 911-991 \/ CARRERA S 2012-2019"}]},{"@type":"WebSite","@id":"https:\/\/europauto2.com\/pt\/#website","url":"https:\/\/europauto2.com\/pt\/","name":"Europauto 2","description":"par IALP Communication","publisher":{"@id":"https:\/\/europauto2.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europauto2.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/europauto2.com\/pt\/#organization","name":"Europauto 2","url":"https:\/\/europauto2.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/europauto2.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/europauto2.com\/wp-content\/uploads\/2023\/09\/IALP-LOGO.webp","contentUrl":"https:\/\/europauto2.com\/wp-content\/uploads\/2023\/09\/IALP-LOGO.webp","width":591,"height":591,"caption":"Europauto 2"},"image":{"@id":"https:\/\/europauto2.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/europauto2.com\/fr\/wp-json\/wp\/v2\/product\/8352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europauto2.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/europauto2.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/europauto2.com\/fr\/wp-json\/wp\/v2\/comments?post=8352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europauto2.com\/fr\/wp-json\/wp\/v2\/media\/17070"}],"wp:attachment":[{"href":"https:\/\/europauto2.com\/fr\/wp-json\/wp\/v2\/media?parent=8352"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/europauto2.com\/fr\/wp-json\/wp\/v2\/product_cat?post=8352"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/europauto2.com\/fr\/wp-json\/wp\/v2\/product_tag?post=8352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}